{"id":6482,"date":"2026-02-25T10:54:10","date_gmt":"2026-02-25T09:54:10","guid":{"rendered":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/rainoldi-angiolina\/"},"modified":"2026-02-25T13:18:39","modified_gmt":"2026-02-25T12:18:39","slug":"rainoldi-angiolina","status":"publish","type":"osoba_jmeno","link":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/rainoldi-angiolina\/","title":{"rendered":"Rainoldi Angiolina"},"author":1,"template":"","class_list":["post-6482","osoba_jmeno","type-osoba_jmeno","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno\/6482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno"}],"about":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/types\/osoba_jmeno"}],"author":[{"embeddable":true,"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/media?parent=6482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}