{"id":5022,"date":"2026-02-25T10:21:39","date_gmt":"2026-02-25T09:21:39","guid":{"rendered":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/caldi-fidel\/"},"modified":"2026-02-25T13:18:26","modified_gmt":"2026-02-25T12:18:26","slug":"caldi-fidel","status":"publish","type":"osoba_jmeno","link":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/caldi-fidel\/","title":{"rendered":"Caldi Fidel"},"author":1,"template":"","class_list":["post-5022","osoba_jmeno","type-osoba_jmeno","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno\/5022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno"}],"about":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/types\/osoba_jmeno"}],"author":[{"embeddable":true,"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/media?parent=5022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}