{"id":4607,"date":"2026-02-25T10:21:35","date_gmt":"2026-02-25T09:21:35","guid":{"rendered":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/etienne-charles-guillaume\/"},"modified":"2026-02-25T13:18:23","modified_gmt":"2026-02-25T12:18:23","slug":"etienne-charles-guillaume","status":"publish","type":"osoba_jmeno","link":"https:\/\/eda.4ws.cz\/index.php\/osoba_jmeno\/etienne-charles-guillaume\/","title":{"rendered":"Etienne Charles-Guillaume"},"author":1,"template":"","class_list":["post-4607","osoba_jmeno","type-osoba_jmeno","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno\/4607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/osoba_jmeno"}],"about":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/types\/osoba_jmeno"}],"author":[{"embeddable":true,"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/eda.4ws.cz\/index.php\/wp-json\/wp\/v2\/media?parent=4607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}